{"id":7628,"date":"2026-05-12T15:31:52","date_gmt":"2026-05-12T15:31:52","guid":{"rendered":"https:\/\/frontrose.gay\/?p=7628"},"modified":"2026-05-12T16:24:01","modified_gmt":"2026-05-12T16:24:01","slug":"y-a-t-il-encore-une-gauche-quebecoise","status":"publish","type":"post","link":"https:\/\/frontrose.gay\/en\/y-a-t-il-encore-une-gauche-quebecoise\/","title":{"rendered":"Y a-t-il encore une gauche qu\u00e9b\u00e9coise ?"},"content":{"rendered":"<h5 class=\"wp-block-heading\">Ce que met en lumi\u00e8re l&rsquo;affaire de la guillotine.<\/h5>\n\n\n\n<p class=\"translation-block\"><em>By <a href=\"https:\/\/frontrose.gay\/en\/author\/louve-rose\/\" target=\"_self\">Louve Rose<\/a><\/em><\/p>\n\n\n\n<p>On ne rentrera pas dans les d\u00e9tails de l&rsquo;histoire de la guillotine d&rsquo;Alliance Ouvri\u00e8re, <a href=\"https:\/\/etoiledunord.media\/2026\/05\/09\/exclusif-des-voix-influentes-rejettent-la-controverse-sur-la-guillotine\/\">d&rsquo;autres l&rsquo;ont d\u00e9j\u00e0 fait<\/a>. \u00c9videmment qu&rsquo;il s&rsquo;agit d&rsquo;une manipulation et d&rsquo;une panique artificielle mont\u00e9es en scandale national par les m\u00e9dias et la classe politique. <\/p>\n\n\n\n<p>Ce qui nous int\u00e9resse ici, c&rsquo;est surtout la r\u00e9action \u00e0 cette histoire de plusieurs acteurices de la \u00ab\u00a0gauche\u00a0\u00bb qu\u00e9b\u00e9coise et ce qu&rsquo;elle r\u00e9v\u00e8le de l&rsquo;\u00e9tat de la politique dans la \u00ab\u00a0belle province\u00a0\u00bb.<\/p>\n\n\n\n<p>Qu\u00e9bec solidaire, les directions de centrales syndicales ainsi que plusieurs intellectuel\u00b7les de \u00ab\u00a0gauche\u00a0\u00bb et plusieurs figures publiques se sont pr\u00e9cipit\u00e9es pour d\u00e9noncer l&rsquo;action aussi rapidement que possible et pour la qualifier de \u00ab grande violence politique \u00bb.\u00a0\u00c0 ce titre, la validation par la gauche de ces discours de droite ne participe qu&rsquo;\u00e0 la l\u00e9gitimation de ce narratif et \u00e0 grossir l&rsquo;affaire. Pourtant, il est \u00e9vident que sans ce rabattage m\u00e9diatique et politique personne n&rsquo;aurait retenu l&rsquo;incident.\u00a0<br><br>Alors pourquoi la gauche semble-t-elle s&rsquo;aligner\u00a0sur les opinions et les int\u00e9r\u00eats du centre et de la droite\u202f? D\u00e9j\u00e0, quand je parle de la gauche, je d\u00e9signe l&rsquo;ensemble politique d\u00e9sign\u00e9 \u00e0 gauche au sein de la politique mainstream et \u00ab\u00a0normale\u00a0\u00bb. Il n&rsquo;est \u00e9videmment pas question ici d&rsquo;organisations et de mouvances dites \u00ab\u00a0d&rsquo;extr\u00eame-gauche\u00a0\u00bb, c&rsquo;est-\u00e0-dire anticapitaliste, r\u00e9volutionnaire, etc. Il est aussi question sp\u00e9cifiquement \u2014 et ce sera important plus loin \u2014 des grandes forces de la gauche, de ses figures et de ses directions,\u00a0pas  de l&rsquo;enti\u00e8ret\u00e9\u00a0de celles et ceux qui en sont membres, qui s&rsquo;y impliquent ou qui s&rsquo;y reconnaissent. Historiquement, le camp de la gauche au Qu\u00e9bec a \u00e9t\u00e9 compos\u00e9 des grands syndicats, d&rsquo;appareils politiques, de regroupements communautaires, du mouvement \u00e9tudiant et d&rsquo;un ensemble de figures intellectuelles et culturelles. De ces forces, les centrales syndicales \u00e9taient clairement les plus importantes et puissantes, suivies par les appareils politiques comme le NPD, QS et le PQ \u00e0 une \u00e9poque d\u00e9finitivement\u00a0r\u00e9volue. \u00c0 ce jour, parmi les acteurs de cette gauche, seuls le milieu \u00e9tudiant et le communautaire n&rsquo;ont pas d\u00e9nonc\u00e9 l&rsquo;action d&rsquo;Alliance Ouvri\u00e8re. Ce n&rsquo;est pas \u00e9tonnant de voir les centrales syndicales et Qu\u00e9bec Solidaire trahir leur camp, mais en m\u00eame temps ce geste semble tellement inutile que \u00e7a pousse \u00e0 la r\u00e9flexion.<\/p>\n\n\n\n<p>Nous sommes \u00e0 une \u00e9poque o\u00f9 des gestes criminels comme ceux des Robins des ruelles sont \u00e9minemment populaires et o\u00f9 le meurtre d&rsquo;un PDG aux \u00c9tats-Unis fait de son auteur une figure ador\u00e9e \u00e0 travers le monde. Dans cette \u00e9poque o\u00f9 le fascisme, la pauvret\u00e9, la guerre, la violence d&rsquo;\u00e9tat et toutes sortes de maladies sociales ne cessent de grandir et d&rsquo;\u00e9trangler la population, on aurait pu esp\u00e9rer que les organisations de gauche aient un peu plus de colonne vert\u00e9brale.\u00a0Mais ce serait oublier la d\u00e9connexion totale entre la classe politique qui si\u00e8ge \u00e0 l&rsquo;assembl\u00e9e nationale ou dans les directions syndicales et le reste de la population.<a href=\"https:\/\/iris-recherche.qc.ca\/blogue\/inegalites-de-genre-et-raciales\/affaire-haroun-bouazzi\/\"> Le traitement d&rsquo;Haroun Bouazi<\/a> par son parti avait n\u00e9anmoins d\u00e9j\u00e0 r\u00e9v\u00e9l\u00e9 que QS pr\u00e9f\u00e9rait tenter de plaire aux m\u00e9dias de droite qu&rsquo;\u00e0 son \u00e9lectorat. Tout le jeu des signaux mensongers et des man\u0153uvres de contournement du mouvement des centrales autour des appels du 1er mai nous montre bien comment ces gens-l\u00e0 pensent la politique. S&rsquo;il leur arrive de d\u00e9signer les graves crises de notre temps et d&rsquo;appeler \u00e0 y r\u00e9pondre, les gestes concrets, et m\u00eame les v\u00e9ritables efforts de mise en avant de discours d&rsquo;opposition au syst\u00e8me\u00a0sont enti\u00e8rement absents.<\/p>\n\n\n\n<p>Pourtant, malgr\u00e9 leur effort&nbsp;d&rsquo;apaisement et de limitation de l&rsquo;action, Qu\u00e9bec Solidaire d\u00e9gringole dans les sondages et semble en voie de potentiellement dispara\u00eetre, tandis que les syndicats se font attaquer et d\u00e9sarmer projet de loi apr\u00e8s projet de loi. Leurs actions et strat\u00e9gies ressemblent de plus en plus \u00e0 un suicide politique. Il y a d\u00e9j\u00e0 eu une vraie gauche au Qu\u00e9bec, qui, sans \u00eatre r\u00e9volutionnaire, \u00e9tait capable de d\u00e9signer les ennemis correctement et cherchait \u00e0 prendre part aux mouvements sociaux.&nbsp;<\/p>\n\n\n\n<p>Si notre m\u00e9dia avait exist\u00e9 \u00e0 l&rsquo;\u00e9poque du premier Front Commun, nous aurions assur\u00e9ment critiqu\u00e9 et fait front contre les directions syndicales et les politicien\u00b7nes de gauche du PQ, mais au moins, nous l&rsquo;aurions fait depuis un semblant d&rsquo;affinit\u00e9 politique. Que reste-t-il qui nous unisse \u00e0 elleux \u2014 elleux qui sont suppos\u00e9\u00b7es repr\u00e9senter les volont\u00e9s de changement des d\u00e9poss\u00e9d\u00e9\u00b7es ?\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Alors,&nbsp;la gauche est morte\u202f?<\/strong><\/h2>\n\n\n\n<p>\u00c9videmment que non.\u00a0D\u00e9j\u00e0, les directions de centrales syndicales ne repr\u00e9sentent pas l&rsquo;ensemble de leurs membres et des syndicats affili\u00e9s. Les gr\u00e8ves r\u00e9centes des cols bleus, param\u00e9dics et de secteurs pr\u00e9cis ont montr\u00e9 qu&rsquo;il reste une certaine combativit\u00e9 syndicale (m\u00eame qu&rsquo;elle semble reprendre du poil de la b\u00eate). Cette activit\u00e9 syndicale plus courageuse semble rester assez d\u00e9politis\u00e9e, mais on peut avoir un peu d&rsquo;espoir que le travail de groupes comme Alliance Ouvri\u00e8re, la Grande D\u00e9mission, le CFP, l&rsquo;IWW et d&rsquo;une partie des militant\u00b7es syndicaux\u00b7les puisse r\u00e9ussir, \u00e0 terme, \u00e0 repolitiser ces mouvements. Certains conseils centraux et syndicaux locaux ont d&rsquo;ailleurs mobilis\u00e9 pour la manifestation du 1er mai ind\u00e9pendamment des centrales. Par ailleurs, une tentative de gr\u00e8ve syndicale a lev\u00e9 suffisamment pour qu&rsquo;on puisse croire qu&rsquo;avec un peu plus de temps et de momentum, elle r\u00e9ussisse.<\/p>\n\n\n\n<p>Au-del\u00e0 des syndicats, les deux autres grands acteurs historiques de la gauche\u00a0\u2014 les \u00e9tudiant\u00b7es et les groupes communautaires \u2014 semblent revenir \u00e0 la vie apr\u00e8s une difficile p\u00e9riode avant et pendant la pand\u00e9mie. <a href=\"https:\/\/www.ledevoir.com\/actualites\/societe\/969515\/apres-deux-semaines-greve-milieu-communautaire-prepare-phase-3-mobilisation?\">La gr\u00e8ve du communautaire \u00e0 boute<\/a> nous t\u00e9moigne au minimum de la capacit\u00e9 de mobilisation des groupes communautaires, tandis que la participation de son aile la plus \u00e0 gauche au 1er mai indique qu&rsquo;il existe des \u00e9l\u00e9ments politis\u00e9s capables de rallier une partie du mouvement. De leur c\u00f4t\u00e9, les \u00e9tudiant\u00b7es, notamment via la CRUES, sont de nouveau une v\u00e9ritable force dans l&rsquo;\u00e9chiquier politique qu\u00e9b\u00e9cois. Le succ\u00e8s ou non de l&rsquo;effort de GGI 2027 nous donnera une meilleure id\u00e9e de l&rsquo;\u00e9tendue de ce retour en force, mais on peut d\u00e9j\u00e0 dire que le mouvement est le plus uni, le plus politis\u00e9\u00a0et le plus dynamique qu&rsquo;on l&rsquo;a connu depuis 2015 (je fait fi ici des mobilisations pour le climat qui ont mobilis\u00e9 largement, mais, tant qu&rsquo;\u00e0 moi, pas du fait des organisations \u00e9tudiantes et surtout sans une r\u00e9elle unit\u00e9 politique). En plus de ces deux groupes historiques, tout un nouvel ensemble de forces de gauche, notamment celles issues des mobilisations pour la Palestine, a \u00e9merg\u00e9 dans les derni\u00e8res ann\u00e9es et ne semble pas avoir perdu tout son momentum.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ne quand m\u00eame pas croire trop fort \u00e0 la gauche<\/strong><\/h2>\n\n\n\n<p>Sans chercher \u00e0 critiquer les groupes mentionn\u00e9s plus haut, je veux quand-m\u00eame nuancer ce qui peut paraitre comme un certain enthousiasme en rappelant les limites d&rsquo;une gauche, m\u00eame particuli\u00e8rement mobilis\u00e9e. Le climat politique change et le retour d&rsquo;une certaine gauche nous offre un plus grand espace de jeux et une meilleure chance de voir \u00e9merger de grands mouvements sociaux. Cependant, on est loin des grandes ann\u00e9es de rapport de force entre classes qu&rsquo;a connues la soci\u00e9t\u00e9 qu\u00e9b\u00e9coise. On est aussi dans une fin de r\u00e9gime et le d\u00e9part de la CAQ pourrait laisser place \u00e0 un apaisement social. Ce ne serait pas la premi\u00e8re fois qu&rsquo;une \u00e9lection asphyxie la gauche. Il faut aussi voir la n\u00e9cessit\u00e9 de construire au-del\u00e0 de la gauche une force capable de faire pression sur elle, de la politiser mais aussi de prendre le leadership de l&rsquo;organisation et de l&rsquo;action pour imposer combativit\u00e9 et rythme aux luttes sociales. Il faut\u00a0compter avant tout et surtout sur les forces du camp r\u00e9volutionnaire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Le retour des r\u00e9volutionnaires<\/strong><\/h2>\n\n\n\n<p>Alors que la gauche \u00e9tait \u00e0 terre ou devenait ma\u00eetre de l&rsquo;art de la trahison, on a vu \u00e9merger une constellation d&rsquo;initiatives, d&rsquo;organisations et de mouvements se revendiquant de l&rsquo;anticapitalisme, de l&rsquo;anti-imp\u00e9rialisme, de l&rsquo;anarchisme, du communisme ou de l&rsquo;appellation r\u00e9volutionnaire. Ces groupes sont beaucoup,&nbsp;beaucoup trop nombreux pour les nommer, mais depuis la fin des confinements il est clair qu&rsquo;un certain dynamisme est en place dans cette \u00ab\u00a0gauche\u00a0\u00bb qui n&rsquo;appartient pas \u00e0 la gauche que je nomme plus haut. C&rsquo;est dans cet ensemble large qu&rsquo;il faut placer nos espoirs. Aussi faibles ou isol\u00e9s ces groupes puissent-ils para\u00eetre, leur influence collective grandit de jour en jour; le 1er mai nous l&rsquo;a montr\u00e9. Si ces groupuscules en venaient \u00e0 r\u00e9ussir \u00e0 s&rsquo;organiser, \u00e0 proposer de v\u00e9ritables strat\u00e9gies de lutte et \u00e0 effectuer des rapprochements concrets, il ne serait pas impossible d&rsquo;imaginer voir la province basculer dans une nouvelle phase de conflit social prolong\u00e9 comme elle l&rsquo;a connu pour les 15 premi\u00e8res ann\u00e9es de ce si\u00e8cle et \u00e0 d&rsquo;autres moments auparavant.<br><br>Une ligne doit \u00eatre dress\u00e9e entre les tra\u00eetres, opportunistes, carri\u00e9ristes, centristes et autres faux gauchistes, et les forces r\u00e9elles du mouvement social et du changement. L&rsquo;heure est \u00e0 la clart\u00e9, au s\u00e9rieux et \u00e0 la cr\u00e9ativit\u00e9 pour qu&rsquo;on puisse enfin voir la lumi\u00e8re au bout du tunnel.<br><br>Avec amour et rage&nbsp;<\/p>\n\n\n\n<p>Louve Rose<br><\/p>","protected":false},"excerpt":{"rendered":"<p>On ne rentrera pas dans les d\u00e9tails de l&rsquo;histoire de la guillotine d&rsquo;Alliance Ouvri\u00e8re, d&rsquo;autres l&rsquo;ont d\u00e9j\u00e0 fait. \u00c9videmment qu&rsquo;il s&rsquo;agit d&rsquo;une manipulation et d&rsquo;une panique artificielle mont\u00e9es en scandale national par les m\u00e9dias et la classe politique. <\/p>","protected":false},"author":2,"featured_media":7629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[114,311,111],"tags":[400,138,139,401,135,402,116,399,398,133,158,340],"class_list":["post-7628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-analyse","category-commentaire","tag-alliance-ouvriere","tag-front-rose","tag-frontrose","tag-gauche","tag-montreal","tag-mouvement-etudiant","tag-politique","tag-qs","tag-quebec-solidaire","tag-queer","tag-revolutionnaire","tag-syndicat"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-150x150.jpeg","medium":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-300x148.jpeg","medium_large":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-768x380.jpeg","large":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg","1536x1536":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg","2048x2048":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg","trp-custom-language-flag":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-18x9.jpeg","colormag-highlighted-post":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-392x272.jpeg","colormag-featured-post-medium":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-390x205.jpeg","colormag-featured-post-small":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-130x90.jpeg","colormag-featured-image":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-800x445.jpeg","colormag-default-news":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-150x150.jpeg","colormag-featured-image-large":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg","colormag-elementor-block-extra-large-thumbnail":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg","colormag-elementor-grid-large-thumbnail":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-600x417.jpeg","colormag-elementor-grid-small-thumbnail":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-285x445.jpeg","colormag-elementor-grid-medium-large-thumbnail":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-575x198.jpeg","mailpoet_newsletter_max":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg"},"magazineBlocksPostAuthor":{"name":"Louve Rose","avatar":"https:\/\/secure.gravatar.com\/avatar\/3ac8254a6bf118d2d536dc1fdb852a48d59d322b8a400b7e80713c487f407a43?s=96&d=blank&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"On ne rentrera pas dans les d\u00e9tails de l'histoire de la guillotine d'Alliance Ouvri\u00e8re, d'autres l'ont d\u00e9j\u00e0 fait. \u00c9videmment qu'il s'agit d'une manipulation et d'une panique artificielle mont\u00e9es en scandale national par les m\u00e9dias et la classe politique. ","magazineBlocksPostCategories":["Actualit\u00e9","Analyse","Commentaire"],"magazineBlocksPostViewCount":175,"magazineBlocksPostReadTime":8,"magazine_blocks_featured_image_url":{"full":["https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg",900,445,false],"medium":["https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-300x148.jpeg",300,148,true],"thumbnail":["https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine-150x150.jpeg",150,150,true]},"magazine_blocks_author":{"display_name":"Louve Rose","author_link":"https:\/\/frontrose.gay\/en\/author\/louve-rose\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/3ac8254a6bf118d2d536dc1fdb852a48d59d322b8a400b7e80713c487f407a43?s=96&d=blank&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-114\">Actualit\u00e9<\/a> <a href=\"#\" class=\"category-link category-link-311\">Analyse<\/a> <a href=\"#\" class=\"category-link category-link-111\">Commentaire<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Y a-t-il encore une gauche qu\u00e9b\u00e9coise ? - Front Rose<\/title>\n<meta name=\"description\" content=\"Y a-t-il encore une gauche qu\u00e9b\u00e9coise. Ce que met en lumi\u00e8re l&#039;affaire de la guillotine. On ne rentrera pas dans les d\u00e9tails de l&#039;histoire de la guillotine d&#039;Alliance Ouvri\u00e8re, d&#039;autres l&#039;ont d\u00e9j\u00e0 fait. \u00c9videmment qu&#039;il s&#039;agit d&#039;une manipulation et d&#039;une panique artificielle mont\u00e9es en scandale national par les m\u00e9dias et la classe politique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frontrose.gay\/en\/y-a-t-il-encore-une-gauche-quebecoise\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Y a-t-il encore une gauche qu\u00e9b\u00e9coise ? - Front Rose\" \/>\n<meta property=\"og:description\" content=\"Y a-t-il encore une gauche qu\u00e9b\u00e9coise. Ce que met en lumi\u00e8re l&#039;affaire de la guillotine. On ne rentrera pas dans les d\u00e9tails de l&#039;histoire de la guillotine d&#039;Alliance Ouvri\u00e8re, d&#039;autres l&#039;ont d\u00e9j\u00e0 fait. \u00c9videmment qu&#039;il s&#039;agit d&#039;une manipulation et d&#039;une panique artificielle mont\u00e9es en scandale national par les m\u00e9dias et la classe politique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frontrose.gay\/en\/y-a-t-il-encore-une-gauche-quebecoise\/\" \/>\n<meta property=\"og:site_name\" content=\"Front Rose\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T15:31:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T16:24:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Louve Rose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Louve Rose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/\"},\"author\":{\"name\":\"Louve Rose\",\"@id\":\"https:\/\/frontrose.gay\/#\/schema\/person\/2adca1ae6c979ac671389a900db514f7\"},\"headline\":\"Y a-t-il encore une gauche qu\u00e9b\u00e9coise ?\",\"datePublished\":\"2026-05-12T15:31:52+00:00\",\"dateModified\":\"2026-05-12T16:24:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/\"},\"wordCount\":1584,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/frontrose.gay\/#organization\"},\"image\":{\"@id\":\"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg\",\"keywords\":[\"alliance ouvri\u00e8re\",\"front rose\",\"frontrose\",\"gauche\",\"montreal\",\"mouvement \u00e9tudiant\",\"politique\",\"qs\",\"qu\u00e9bec solidaire\",\"queer\",\"r\u00e9volutionnaire\",\"syndicat\"],\"articleSection\":[\"Actualit\u00e9\",\"Analyse\",\"Commentaire\"],\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/\",\"url\":\"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/\",\"name\":\"Y a-t-il encore une gauche qu\u00e9b\u00e9coise ? - Front Rose\",\"isPartOf\":{\"@id\":\"https:\/\/frontrose.gay\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg\",\"datePublished\":\"2026-05-12T15:31:52+00:00\",\"dateModified\":\"2026-05-12T16:24:01+00:00\",\"description\":\"Y a-t-il encore une gauche qu\u00e9b\u00e9coise. Ce que met en lumi\u00e8re l'affaire de la guillotine. On ne rentrera pas dans les d\u00e9tails de l'histoire de la guillotine d'Alliance Ouvri\u00e8re, d'autres l'ont d\u00e9j\u00e0 fait. \u00c9videmment qu'il s'agit d'une manipulation et d'une panique artificielle mont\u00e9es en scandale national par les m\u00e9dias et la classe politique.\",\"breadcrumb\":{\"@id\":\"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#primaryimage\",\"url\":\"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg\",\"contentUrl\":\"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg\",\"width\":900,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/frontrose.gay\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Y a-t-il encore une gauche qu\u00e9b\u00e9coise ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/frontrose.gay\/#website\",\"url\":\"https:\/\/frontrose.gay\/\",\"name\":\"Front Rose\",\"description\":\"Front Rose n&#039;est pas un magazine de lifestyle queer\",\"publisher\":{\"@id\":\"https:\/\/frontrose.gay\/#organization\"},\"alternateName\":\"frontrose\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/frontrose.gay\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/frontrose.gay\/#organization\",\"name\":\"Front Rose\",\"alternateName\":\"frontrose\",\"url\":\"https:\/\/frontrose.gay\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\/\/frontrose.gay\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/frontrose.gay\/wp-content\/uploads\/2025\/02\/cropped-cropped-cropped-cropped-frontrose_logo_web-2.png\",\"contentUrl\":\"https:\/\/frontrose.gay\/wp-content\/uploads\/2025\/02\/cropped-cropped-cropped-cropped-frontrose_logo_web-2.png\",\"width\":958,\"height\":196,\"caption\":\"Front Rose\"},\"image\":{\"@id\":\"https:\/\/frontrose.gay\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/frontrose.gay\/#\/schema\/person\/2adca1ae6c979ac671389a900db514f7\",\"name\":\"Louve Rose\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\/\/frontrose.gay\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3ac8254a6bf118d2d536dc1fdb852a48d59d322b8a400b7e80713c487f407a43?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3ac8254a6bf118d2d536dc1fdb852a48d59d322b8a400b7e80713c487f407a43?s=96&d=blank&r=g\",\"caption\":\"Louve Rose\"},\"url\":\"https:\/\/frontrose.gay\/en\/author\/louve-rose\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Y a-t-il encore une gauche qu\u00e9b\u00e9coise ? - Front Rose","description":"Y a-t-il encore une gauche qu\u00e9b\u00e9coise. Ce que met en lumi\u00e8re l'affaire de la guillotine. On ne rentrera pas dans les d\u00e9tails de l'histoire de la guillotine d'Alliance Ouvri\u00e8re, d'autres l'ont d\u00e9j\u00e0 fait. \u00c9videmment qu'il s'agit d'une manipulation et d'une panique artificielle mont\u00e9es en scandale national par les m\u00e9dias et la classe politique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frontrose.gay\/en\/y-a-t-il-encore-une-gauche-quebecoise\/","og_locale":"en_US","og_type":"article","og_title":"Y a-t-il encore une gauche qu\u00e9b\u00e9coise ? - Front Rose","og_description":"Y a-t-il encore une gauche qu\u00e9b\u00e9coise. Ce que met en lumi\u00e8re l'affaire de la guillotine. On ne rentrera pas dans les d\u00e9tails de l'histoire de la guillotine d'Alliance Ouvri\u00e8re, d'autres l'ont d\u00e9j\u00e0 fait. \u00c9videmment qu'il s'agit d'une manipulation et d'une panique artificielle mont\u00e9es en scandale national par les m\u00e9dias et la classe politique.","og_url":"https:\/\/frontrose.gay\/en\/y-a-t-il-encore-une-gauche-quebecoise\/","og_site_name":"Front Rose","article_published_time":"2026-05-12T15:31:52+00:00","article_modified_time":"2026-05-12T16:24:01+00:00","og_image":[{"width":900,"height":445,"url":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg","type":"image\/jpeg"}],"author":"Louve Rose","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Louve Rose","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#article","isPartOf":{"@id":"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/"},"author":{"name":"Louve Rose","@id":"https:\/\/frontrose.gay\/#\/schema\/person\/2adca1ae6c979ac671389a900db514f7"},"headline":"Y a-t-il encore une gauche qu\u00e9b\u00e9coise ?","datePublished":"2026-05-12T15:31:52+00:00","dateModified":"2026-05-12T16:24:01+00:00","mainEntityOfPage":{"@id":"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/"},"wordCount":1584,"commentCount":0,"publisher":{"@id":"https:\/\/frontrose.gay\/#organization"},"image":{"@id":"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#primaryimage"},"thumbnailUrl":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg","keywords":["alliance ouvri\u00e8re","front rose","frontrose","gauche","montreal","mouvement \u00e9tudiant","politique","qs","qu\u00e9bec solidaire","queer","r\u00e9volutionnaire","syndicat"],"articleSection":["Actualit\u00e9","Analyse","Commentaire"],"inLanguage":"en-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/","url":"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/","name":"Y a-t-il encore une gauche qu\u00e9b\u00e9coise ? - Front Rose","isPartOf":{"@id":"https:\/\/frontrose.gay\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#primaryimage"},"image":{"@id":"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#primaryimage"},"thumbnailUrl":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg","datePublished":"2026-05-12T15:31:52+00:00","dateModified":"2026-05-12T16:24:01+00:00","description":"Y a-t-il encore une gauche qu\u00e9b\u00e9coise. Ce que met en lumi\u00e8re l'affaire de la guillotine. On ne rentrera pas dans les d\u00e9tails de l'histoire de la guillotine d'Alliance Ouvri\u00e8re, d'autres l'ont d\u00e9j\u00e0 fait. \u00c9videmment qu'il s'agit d'une manipulation et d'une panique artificielle mont\u00e9es en scandale national par les m\u00e9dias et la classe politique.","breadcrumb":{"@id":"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#primaryimage","url":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg","contentUrl":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg","width":900,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/frontrose.gay\/y-a-t-il-encore-une-gauche-quebecoise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/frontrose.gay\/"},{"@type":"ListItem","position":2,"name":"Y a-t-il encore une gauche qu\u00e9b\u00e9coise ?"}]},{"@type":"WebSite","@id":"https:\/\/frontrose.gay\/#website","url":"https:\/\/frontrose.gay\/","name":"Front Rose","description":"Front Rose n&#039;est pas un magazine de lifestyle queer","publisher":{"@id":"https:\/\/frontrose.gay\/#organization"},"alternateName":"frontrose","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frontrose.gay\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/frontrose.gay\/#organization","name":"Front Rose","alternateName":"frontrose","url":"https:\/\/frontrose.gay\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/frontrose.gay\/#\/schema\/logo\/image\/","url":"https:\/\/frontrose.gay\/wp-content\/uploads\/2025\/02\/cropped-cropped-cropped-cropped-frontrose_logo_web-2.png","contentUrl":"https:\/\/frontrose.gay\/wp-content\/uploads\/2025\/02\/cropped-cropped-cropped-cropped-frontrose_logo_web-2.png","width":958,"height":196,"caption":"Front Rose"},"image":{"@id":"https:\/\/frontrose.gay\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/frontrose.gay\/#\/schema\/person\/2adca1ae6c979ac671389a900db514f7","name":"Louve Rose","image":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/frontrose.gay\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3ac8254a6bf118d2d536dc1fdb852a48d59d322b8a400b7e80713c487f407a43?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ac8254a6bf118d2d536dc1fdb852a48d59d322b8a400b7e80713c487f407a43?s=96&d=blank&r=g","caption":"Louve Rose"},"url":"https:\/\/frontrose.gay\/en\/author\/louve-rose\/"}]}},"jetpack_featured_media_url":"https:\/\/frontrose.gay\/wp-content\/uploads\/2026\/05\/guillotine.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/frontrose.gay\/en\/wp-json\/wp\/v2\/posts\/7628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frontrose.gay\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frontrose.gay\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frontrose.gay\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/frontrose.gay\/en\/wp-json\/wp\/v2\/comments?post=7628"}],"version-history":[{"count":2,"href":"https:\/\/frontrose.gay\/en\/wp-json\/wp\/v2\/posts\/7628\/revisions"}],"predecessor-version":[{"id":7632,"href":"https:\/\/frontrose.gay\/en\/wp-json\/wp\/v2\/posts\/7628\/revisions\/7632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frontrose.gay\/en\/wp-json\/wp\/v2\/media\/7629"}],"wp:attachment":[{"href":"https:\/\/frontrose.gay\/en\/wp-json\/wp\/v2\/media?parent=7628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frontrose.gay\/en\/wp-json\/wp\/v2\/categories?post=7628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frontrose.gay\/en\/wp-json\/wp\/v2\/tags?post=7628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}